{"id":1288,"date":"2018-07-16T18:19:49","date_gmt":"2018-07-16T16:19:49","guid":{"rendered":"http:\/\/www.omongateau.fr\/?p=1288"},"modified":"2022-08-29T14:34:19","modified_gmt":"2022-08-29T12:34:19","slug":"black-forest","status":"publish","type":"post","link":"https:\/\/www.omongateau.fr\/index.php\/2018\/07\/16\/black-forest\/","title":{"rendered":"Black forest"},"content":{"rendered":"<p>J&rsquo;estime ne pas encore \u00eatre tr\u00e8s dou\u00e9 dans l&rsquo;art de la revisite. J&rsquo;ai\u00a0 besoin de temps pour cr\u00e9er,\u00a0 pour r\u00e9fl\u00e9chir, pour imaginer et enfin trouver l&rsquo;id\u00e9e. Il y a peu, je me suis r\u00e9veill\u00e9 avec une image de revisite de for\u00eat noire en t\u00eate. C&rsquo;est un g\u00e2teau que j&rsquo;aime beaucoup quand il est l\u00e9ger et pas trop alcoolis\u00e9. Je connais une recette d&rsquo;un biscuit cacao sans farine ultra moelleux et humide, une petite mousse vanille Kirsh bien dos\u00e9e et une compot\u00e9e de griottes fondante et pas trop coll\u00e9e. J&rsquo;ai mis tout cela sur papier, j&rsquo;ai trouv\u00e9 le nom tr\u00e8s simple de Black forest et\u00a0 je suis pass\u00e9 en cuisine.<\/p>\n<p>Les amis : recette !<\/p>\n<ul>\n<li><b>Materiel utilis\u00e9<br \/>\n<\/b>Pour cette r\u00e9alisation, j\u2019ai utilis\u00e9 plusieurs mat\u00e9riels que vous trouverez sur la boutique de mon partenaire <a href=\"https:\/\/www.panierdeschefs.eu\/\" target=\"_blank\" rel=\"noopener\">Panier des Chefs.<\/a>\u00a0(N\u2019oubliez-pas que je vous fais b\u00e9n\u00e9ficier d\u2019une remise de 10% sur cette boutique avec le code <strong>CLEMENT-10<\/strong>\u00a0)<br \/>\n<span style=\"font-size: 12pt;\">&#8211; <a href=\"https:\/\/www.panierdeschefs.eu\/power-flowers-panier-des-chefs\/5685-rouge-scintillant-power-flower-sparkling-non-azo-50g.html?search_query=sparkling&amp;results=1\" target=\"_blank\" rel=\"noopener\">Power Flowers rouge scintillant<\/a> <span style=\"font-size: 10pt;\"><em><br \/>\n<\/em><\/span><\/span><span style=\"font-size: 12pt;\">&#8211; <a href=\"https:\/\/www.panierdeschefs.eu\/chocolart-colorants-en-poudre\/5124-noir-colorant-en-poudre-chocolart-40g-pavoni-italia.html?search_query=chocolart&amp;results=22\" target=\"_blank\" rel=\"noopener\">Pavoni &#8211; Noir &#8211; Colorant en poudre &#8211; Chocolart<\/a><\/span><br \/>\n<span style=\"font-size: 12pt;\">&#8211; <a href=\"https:\/\/www.panierdeschefs.eu\/pavoflex-300x400\/5453-pavoni-moule-en-silicone-loop-pavoflex.html\" target=\"_blank\" rel=\"noopener\">Pavoni &#8211; Loop Pavoflex &#8211; 12 empreintes<\/a><br \/>\n<\/span>&#8211; <a href=\"https:\/\/www.panierdeschefs.eu\/cercles-a-tarte-crostate\/3740-tapis-en-silicone-micro-perfore-crostate.html?search_query=Tapis+en+silicone+micro+perfore+-+Crostate&amp;results=2682\" target=\"_blank\" rel=\"noopener\">Pavoni &#8211; Tapis en silicone microperfor\u00e9 &#8211; Crostate<\/a><br \/>\n&#8211; <a href=\"http:\/\/www.robot-coupe.com\/fr-fr\/catalogue\/robot-cook,24470\/\" target=\"_blank\" rel=\"noopener\">Robot-Cook de chez Robot-Coupe<\/a><\/li>\n<\/ul>\n<p><span style=\"font-size: 10pt;\"><strong><em>(pour 11 petits g\u00e2teaux)<\/em><\/strong><\/span><\/p>\n<ul>\n<li><b>Compot\u00e9e de griottes<br \/>\n<\/b>&#8211; 35g de masse g\u00e9latine 200 bloom<br \/>\n&#8211; 300g de pur\u00e9e de griottes<br \/>\n&#8211; 65g de sucre inverti<br \/>\n&#8211; 20g de sucre en poudre<br \/>\n&#8211; 5g de pectine NH<br \/>\n&#8211; 5g de jus de citron<\/li>\n<\/ul>\n<p>Pr\u00e9parer la masse g\u00e9latine en hydratant 5g de g\u00e9latine en poudre dans 30g d&rsquo;eau. Faire chauffer dans une casserole la pur\u00e9e de griottes avec le sucre inverti. Aux premi\u00e8res vapeurs, ajouter le m\u00e9lange sucre et pectine et bien m\u00e9langer. Ajouter la masse g\u00e9latine et la faire fondre. Porter \u00e0 \u00e9bullition 1minute. Hors du feu ajouter le jus de citron. Mettre 24g d&rsquo;appareil dans chaque empreinte du moule Pavoflex Loop Pavoni. Faire prendre au cong\u00e9lateur. Une fois pris, d\u00e9mouler et r\u00e9server au cong\u00e9lateur afin de r\u00e9cup\u00e9rer le moule.<\/p>\n<div class=\" gallery wolf-images-gallery clearfix simple-gallery hover-default padding gallery-2-columns\" id=\"gallery-929\" style=\"\"><div class='block'><a title=\"\" href=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-05.jpg\" class=\"lightbox image-item\" rel=\"gallery-929\"><img src=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-05-960x480.jpg\" alt=\"BlackForest-05\"><\/a><\/div><div class='block'><a title=\"\" href=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-06.jpg\" class=\"lightbox image-item\" rel=\"gallery-929\"><img src=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-06-960x480.jpg\" alt=\"BlackForest-06\"><\/a><\/div><\/div>\n<p>&nbsp;<\/p>\n<ul>\n<li><b>Biscuit cacao Inaya<br \/>\n<\/b><span style=\"font-size: 10pt;\"><em>(recette de <strong>Chef Philippe<\/strong> du site <strong>www.meilleurduchef.com<\/strong>)<\/em><\/span><br \/>\n&#8211; 110g de chocolat noir Inaya CacaoBarry<br \/>\n&#8211; 6 oeufs<br \/>\n&#8211; 130g de p\u00e2te d&rsquo;amande blanche<br \/>\n&#8211; 160g de de sucre en poudre<\/li>\n<\/ul>\n<p>Pr\u00e9chauffer le four \u00e0 180\u00b0C. S\u00e9parer les blancs des jaunes d\u2019\u0153ufs. Faire fondre le chocolat noir Inaya. Mettre les jaunes d\u2019\u0153ufs et la patte d&rsquo;amande en petits morceaux dans le robot coupe et mixer jusqu&rsquo;\u00e0 obtenir une p\u00e2te bien homog\u00e8ne. Vous pouvez utiliser n&rsquo;importe quel autre mixeur. Ajouter le chocolat fondu et bien m\u00e9langer. Monter les blancs en neige et les serrer avec le sucre en poudre. Incorporer d\u00e9licatement \u00e0 la maryse l&rsquo;appareil chocolat\u00e9 aux blancs mont\u00e9s. Coul\u00e9 dans un cadre graiss\u00e9 de 22&#215;22. Cuire au four \u00e0 180\u00b0C 35 minutes. La pointe du couteau doit ressorti s\u00e8che. Le sortir du four et le laisser refroidir sur une grille. C&rsquo;est un biscuit tr\u00e8s l\u00e9ger mais tr\u00e8s d\u00e9licat \u00e0 manipuler. D\u00e9tailler le biscuit refroidit avec un emporte pi\u00e8ce rond correspondant au diam\u00e8tre du moule. Les morceaux sont \u00e9pais, donc on les tranchera en 2 dans l&rsquo;\u00e9paisseur \u00e0 l&rsquo;aide d&rsquo;un couteau \u00e0 g\u00e9noise. \u00c9vider le centre avec un 2\u00e8me emporte pi\u00e8ce plus petit correspondant lui aussi au moule. R\u00e9server.<\/p>\n<div class=\" gallery wolf-images-gallery clearfix simple-gallery hover-default padding gallery-4-columns\" id=\"gallery-573\" style=\"\"><div class='block'><a title=\"\" href=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-16.jpg\" class=\"lightbox image-item\" rel=\"gallery-573\"><img src=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-16-960x480.jpg\" alt=\"BlackForest-16\"><\/a><\/div><div class='block'><a title=\"\" href=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-17.jpg\" class=\"lightbox image-item\" rel=\"gallery-573\"><img src=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-17-960x480.jpg\" alt=\"BlackForest-17\"><\/a><\/div><div class='block'><a title=\"\" href=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-09.jpg\" class=\"lightbox image-item\" rel=\"gallery-573\"><img src=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-09-960x480.jpg\" alt=\"BlackForest-09\"><\/a><\/div><div class='block'><a title=\"\" href=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-18.jpg\" class=\"lightbox image-item\" rel=\"gallery-573\"><img src=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-18-960x480.jpg\" alt=\"BlackForest-18\"><\/a><\/div><div class='block'><a title=\"\" href=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-08.jpg\" class=\"lightbox image-item\" rel=\"gallery-573\"><img src=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-08-960x480.jpg\" alt=\"BlackForest-08\"><\/a><\/div><div class='block'><a title=\"\" href=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-19.jpg\" class=\"lightbox image-item\" rel=\"gallery-573\"><img src=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-19-960x480.jpg\" alt=\"BlackForest-19\"><\/a><\/div><div class='block'><a title=\"\" href=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-10.jpg\" class=\"lightbox image-item\" rel=\"gallery-573\"><img src=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-10-960x480.jpg\" alt=\"BlackForest-10\"><\/a><\/div><div class='block'><a title=\"\" href=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-11.jpg\" class=\"lightbox image-item\" rel=\"gallery-573\"><img src=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-11-960x480.jpg\" alt=\"BlackForest-11\"><\/a><\/div><div class='block'><a title=\"\" href=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-15.jpg\" class=\"lightbox image-item\" rel=\"gallery-573\"><img src=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-15-960x480.jpg\" alt=\"BlackForest-15\"><\/a><\/div><div class='block'><a title=\"\" href=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-14.jpg\" class=\"lightbox image-item\" rel=\"gallery-573\"><img src=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-14-960x480.jpg\" alt=\"BlackForest-14\"><\/a><\/div><\/div>\n<ul>\n<li><b>Mousse vanille Kirsh<\/b><br \/>\n&#8211; 220g de lait<br \/>\n&#8211; 1 gousse de vanille<br \/>\n&#8211; 50g de jaune d&rsquo;oeuf<br \/>\n&#8211; 40g de sucre semoule<br \/>\n&#8211; 35g de masse g\u00e9latine<br \/>\n&#8211; 20g de Kirsh<br \/>\n&#8211; 220g de cr\u00e8me 35%<\/li>\n<\/ul>\n<p>Pr\u00e9parer la masse g\u00e9latine en hydratant 5g de g\u00e9latine en poudre dans 30g d&rsquo;eau. Faire chauffer le lait et 20g de sucre dans une casserole avec la gousse de vanille fendue et gratt\u00e9e. Ajouter la masse g\u00e9latine et faire fondre. Laisser infuser \u00e0 couvert pendant 20 minutes. Blanchir les jaunes d\u2019\u0153ufs avec les 20g de sucre de restant. Refaire chauffer le lait et \u00e0 fr\u00e9missement, verser sur les jaunes d\u2019\u0153ufs blanchis. Bien m\u00e9langer et reverser dans la casserole pour faire cuire \u00e0 83\u00b0c. Chinoiser, ajouter le Kirsh, m\u00e9langer et r\u00e9server pour faire refroidir \u00e0 20\u00b0C. Monter la cr\u00e8me bien froide au batteur muni du fouet. Incorporer la premi\u00e8re pr\u00e9paration d\u00e9licatement \u00e0 la maryse. Mettre en poche sans douille. Nous sommes pr\u00eats pour le montage.<\/p>\n<div class=\" gallery wolf-images-gallery clearfix simple-gallery hover-default padding gallery-3-columns\" id=\"gallery-734\" style=\"\"><div class='block'><a title=\"\" href=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-21.jpg\" class=\"lightbox image-item\" rel=\"gallery-734\"><img src=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-21-960x480.jpg\" alt=\"BlackForest-21\"><\/a><\/div><div class='block'><a title=\"\" href=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-20.jpg\" class=\"lightbox image-item\" rel=\"gallery-734\"><img src=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-20-960x480.jpg\" alt=\"BlackForest-20\"><\/a><\/div><div class='block'><a title=\"\" href=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-12.jpg\" class=\"lightbox image-item\" rel=\"gallery-734\"><img src=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-12-960x480.jpg\" alt=\"BlackForest-12\"><\/a><\/div><\/div>\n<ul>\n<li><b>Montage 1<\/b><br \/>\n&#8211; insert congel\u00e9 griotte<br \/>\n&#8211; biscuit cacao<br \/>\n&#8211; mousse vanille Kirsh<\/li>\n<\/ul>\n<p>Verser dans les empreintes du moule Pavoni Pavoflex loop un peu de mousse vanille. Plonger l&rsquo;insert griotte en appuyant l\u00e9g\u00e8rement pour faire remonter la mousse mais sans lui faire toucher le fond. Faire retomber la mousse sur l&rsquo;insert. Mettre 1 biscuit cacao par empreinte. Combler avec le reste de mousse si n\u00e9cessaire et lisser \u00e0 la spatule. Faire prendre au cong\u00e9lateur pendant 6h.<\/p>\n<div class=\" gallery wolf-images-gallery clearfix simple-gallery hover-default padding gallery-3-columns\" id=\"gallery-887\" style=\"\"><div class='block'><a title=\"\" href=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-13.jpg\" class=\"lightbox image-item\" rel=\"gallery-887\"><img src=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-13-960x480.jpg\" alt=\"BlackForest-13\"><\/a><\/div><div class='block'><a title=\"\" href=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-22.jpg\" class=\"lightbox image-item\" rel=\"gallery-887\"><img src=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-22-960x480.jpg\" alt=\"BlackForest-22\"><\/a><\/div><div class='block'><a title=\"\" href=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-28.jpg\" class=\"lightbox image-item\" rel=\"gallery-887\"><img src=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-28-960x480.jpg\" alt=\"BlackForest-28\"><\/a><\/div><\/div>\n<ul>\n<li><b>P\u00e2te sabl\u00e9e cacao<\/b><br \/>\n&#8211; 160g de beurre<br \/>\n&#8211; 70g de sucre glace<br \/>\n&#8211; 2g de fleur de sel<br \/>\n&#8211; 90g de poudre d&rsquo;amande<br \/>\n&#8211; 140g de farine T55<br \/>\n&#8211; 25g de poudre de cacao<br \/>\n&#8211; 25g d&rsquo;oeuf<br \/>\n&#8211; QS de colorant en poudre noir lipo<\/li>\n<\/ul>\n<p>Mettre le beurre en petit morceaux,\u00a0 le sucre glace, la fleur de sel et la poudre de cacao dans la cuve du batteur muni de la feuille. Battre jusqu&rsquo;\u00e0 l&rsquo;obtention d&rsquo; une texture cr\u00e9meuse homog\u00e8ne. Ralentir le robot et ajouter l\u2019\u0153uf, puis la poudre d&rsquo;amande. Terminer par la farine tamis\u00e9e et stopper le robot d\u00e8s que la p\u00e2te est homog\u00e8ne. Fraser la p\u00e2te sur le plan de travail.\u00a0La rassembler pour former une boule aplatie. Filmer au contact. Laisser reposer minimum 1h au frais. Pr\u00e9chauffer le four \u00e0 160\u00b0C.\u00a0 Abaisser la p\u00e2te sur 3mm d&rsquo;\u00e9paisseur et d\u00e9tailler des disques de 7cm de diam\u00e8tre. Remettre au frais pendant 15 minimum. Sur un tapis silicone microperfor\u00e9, cuire au four pendant 15 minutes \u00e0 160\u00b0C. Sortir et laisser refroidir sur une grille.<\/p>\n<div class=\" gallery wolf-images-gallery clearfix simple-gallery hover-default padding gallery-5-columns\" id=\"gallery-511\" style=\"\"><div class='block'><a title=\"\" href=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-23.jpg\" class=\"lightbox image-item\" rel=\"gallery-511\"><img src=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-23-960x480.jpg\" alt=\"BlackForest-23\"><\/a><\/div><div class='block'><a title=\"\" href=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-24.jpg\" class=\"lightbox image-item\" rel=\"gallery-511\"><img src=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-24-960x480.jpg\" alt=\"BlackForest-24\"><\/a><\/div><div class='block'><a title=\"\" href=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-25.jpg\" class=\"lightbox image-item\" rel=\"gallery-511\"><img src=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-25-960x480.jpg\" alt=\"BlackForest-25\"><\/a><\/div><div class='block'><a title=\"\" href=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-26.jpg\" class=\"lightbox image-item\" rel=\"gallery-511\"><img src=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-26-960x480.jpg\" alt=\"BlackForest-26\"><\/a><\/div><div class='block'><a title=\"\" href=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-27.jpg\" class=\"lightbox image-item\" rel=\"gallery-511\"><img src=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-27-960x480.jpg\" alt=\"BlackForest-27\"><\/a><\/div><\/div>\n<ul>\n<li><b>Gla\u00e7age bicolore<\/b><br \/>\n&#8211; 140g de masse g\u00e9latine 200 bloom<br \/>\n&#8211; 190g de lait concentr\u00e9 sucr\u00e9<br \/>\n&#8211; 300g de chocolat noir Equateur Cacaobarry<br \/>\n&#8211; 300g de glucose<br \/>\n&#8211; 300g de sucre en poudre<br \/>\n&#8211; 150g d&rsquo;eau<br \/>\n&#8211; QS de colorant en poudre noir lipo<br \/>\n&#8211; 4 Power flowers Rouge scintillant<\/li>\n<\/ul>\n<p style=\"text-align: left;\">R\u00e9aliser la masse g\u00e9latine en hydratant 20g de g\u00e9latine en poudre 200 bloom dans 120g d&rsquo;eau. Dans un grand pichet, mettre le lait concentr\u00e9 sucr\u00e9, la masse g\u00e9latine et le chocolat. Dans une casserole faire un sirop \u00e0 103\u00b0C avec l&rsquo;eau, le glucose et le sucre. Le verser dans le pichet et mixer \u00e0 l&rsquo;aide d&rsquo;un mixeur plongeant. Diviser le gla\u00e7age en 2. Colorer le premier en noir et le 2\u00e8me en rouge scintillant. Mixer \u00e0 nouveau. Faire refroidir les gla\u00e7age \u00e0 32\u00b0C<br \/>\n<a href=\"http:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-07.jpg\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-1296\" src=\"http:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-07.jpg\" alt=\"\" width=\"991\" height=\"576\" srcset=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-07.jpg 991w, https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-07-300x174.jpg 300w, https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-07-768x446.jpg 768w, https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-07-645x375.jpg 645w, https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-07-640x372.jpg 640w\" sizes=\"(max-width: 991px) 100vw, 991px\" \/><\/a><\/p>\n<ul>\n<li><b>Montage 2<\/b><br \/>\n&#8211; Entremets individuels congel\u00e9s<br \/>\n&#8211; Disques de p\u00e2te sucr\u00e9e cacao<br \/>\n&#8211; Gla\u00e7age<br \/>\n&#8211; Copeaux de chocolat<br \/>\n&#8211; Cerises fraiches<br \/>\n&#8211; Feuille d&rsquo;or<\/li>\n<\/ul>\n<p>Planter un petit pic en bois dans chaque entremets congel\u00e9s et les disposer sur une grille au dessus d&rsquo;une plaque recouverte de papier film qui r\u00e9cup\u00e9rera l&rsquo;exc\u00e9dent de gla\u00e7age. Verser dans un 3\u00e8me pichet un peu de gla\u00e7age noir et de gla\u00e7age rouge scintillant en m\u00eame temps. A l&rsquo;aide d&rsquo;un grand pic en bois m\u00e9langer tr\u00e8s tr\u00e8s peu (il ne faut pas que les couleurs se fusionnent). Verser sur l&rsquo;entremets congel\u00e9s en faisant des va et vient pour z\u00e9brer l&rsquo;entremets. Attendre que le gla\u00e7age coule et \u00e0 l&rsquo;aide du pic en bois plant\u00e9 le d\u00e9poser sur un disque de p\u00e2te sabl\u00e9e cacao. Mettre des copeaux de chocolat, une cerise dans le creux et une touche de feuille d&rsquo;or. Laisser d\u00e9congeler 2h au frigo.<\/p>\n<p>R\u00e9galez-vous !<\/p>\n<div class=\" gallery wolf-images-gallery clearfix simple-gallery hover-default padding gallery-4-columns\" id=\"gallery-223\" style=\"\"><div class='block'><a title=\"\" href=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-01.jpg\" class=\"lightbox image-item\" rel=\"gallery-223\"><img src=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-01-960x480.jpg\" alt=\"BlackForest-01\"><\/a><\/div><div class='block'><a title=\"\" href=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-03.jpg\" class=\"lightbox image-item\" rel=\"gallery-223\"><img src=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-03-960x480.jpg\" alt=\"BlackForest-03\"><\/a><\/div><div class='block'><a title=\"\" href=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-02.jpg\" class=\"lightbox image-item\" rel=\"gallery-223\"><img src=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-02-960x480.jpg\" alt=\"BlackForest-02\"><\/a><\/div><div class='block'><a title=\"\" href=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-04.jpg\" class=\"lightbox image-item\" rel=\"gallery-223\"><img src=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-04-960x480.jpg\" alt=\"BlackForest-04\"><\/a><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>J&rsquo;estime ne pas encore \u00eatre tr\u00e8s dou\u00e9 dans l&rsquo;art de la revisite. J&rsquo;ai\u00a0 besoin de temps pour cr\u00e9er,\u00a0 pour r\u00e9fl\u00e9chir, pour imaginer et enfin trouver l&rsquo;id\u00e9e. Il y a peu, je me suis r\u00e9veill\u00e9 avec une image de revisite de for\u00eat noire en t\u00eate. C&rsquo;est un g\u00e2teau que j&rsquo;aime beaucoup quand il est l\u00e9ger et&#8230;<\/p>\n<p><a rel=\"bookmark\" class=\"more-link more-link wolf-button\" href=\"https:\/\/www.omongateau.fr\/index.php\/2018\/07\/16\/black-forest\/\">Lire la suite &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":1291,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[207],"tags":[81,30,85,86,47,87],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Black forest - Revisite de la for\u00eat noire - \u00d4 mon G\u00e2teau - Cl\u00e9ment Lhoumeau<\/title>\n<meta name=\"description\" content=\"Apprenez la recette de ce petit g\u00e2teau compos\u00e9 d&#039;une p\u00e2te sabl\u00e9e cacao, d&#039;un biscuit moelleux cacao, d&#039;une mousse au kirsh et d&#039;une compot\u00e9e de griottes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.omongateau.fr\/index.php\/2018\/07\/16\/black-forest\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Black forest - Revisite de la for\u00eat noire - \u00d4 mon G\u00e2teau - Cl\u00e9ment Lhoumeau\" \/>\n<meta property=\"og:description\" content=\"Apprenez la recette de ce petit g\u00e2teau compos\u00e9 d&#039;une p\u00e2te sabl\u00e9e cacao, d&#039;un biscuit moelleux cacao, d&#039;une mousse au kirsh et d&#039;une compot\u00e9e de griottes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.omongateau.fr\/index.php\/2018\/07\/16\/black-forest\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00d4 mon G\u00e2teau\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-16T16:19:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-29T12:34:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-02.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\">\n\t<meta name=\"twitter:data1\" content=\"5 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.omongateau.fr\/#website\",\"url\":\"https:\/\/www.omongateau.fr\/\",\"name\":\"\\u00d4 mon G\\u00e2teau\",\"description\":\"P\\u00e2tisseries fa\\u00eetes avec passion\",\"publisher\":{\"@id\":\"https:\/\/www.omongateau.fr\/#\/schema\/person\/f4bcddbd180028225e24bc6f070a2a3c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.omongateau.fr\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.omongateau.fr\/index.php\/2018\/07\/16\/black-forest\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/07\/BlackForest-02.jpg\",\"width\":1024,\"height\":683},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.omongateau.fr\/index.php\/2018\/07\/16\/black-forest\/#webpage\",\"url\":\"https:\/\/www.omongateau.fr\/index.php\/2018\/07\/16\/black-forest\/\",\"name\":\"Black forest - Revisite de la for\\u00eat noire - \\u00d4 mon G\\u00e2teau - Cl\\u00e9ment Lhoumeau\",\"isPartOf\":{\"@id\":\"https:\/\/www.omongateau.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.omongateau.fr\/index.php\/2018\/07\/16\/black-forest\/#primaryimage\"},\"datePublished\":\"2018-07-16T16:19:49+00:00\",\"dateModified\":\"2022-08-29T12:34:19+00:00\",\"description\":\"Apprenez la recette de ce petit g\\u00e2teau compos\\u00e9 d'une p\\u00e2te sabl\\u00e9e cacao, d'un biscuit moelleux cacao, d'une mousse au kirsh et d'une compot\\u00e9e de griottes.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.omongateau.fr\/index.php\/2018\/07\/16\/black-forest\/\"]}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/www.omongateau.fr\/index.php\/2018\/07\/16\/black-forest\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.omongateau.fr\/index.php\/2018\/07\/16\/black-forest\/#webpage\"},\"author\":{\"@id\":\"https:\/\/www.omongateau.fr\/#\/schema\/person\/f4bcddbd180028225e24bc6f070a2a3c\"},\"headline\":\"Black forest\",\"datePublished\":\"2018-07-16T16:19:49+00:00\",\"dateModified\":\"2022-08-29T12:34:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.omongateau.fr\/index.php\/2018\/07\/16\/black-forest\/#webpage\"},\"commentCount\":4,\"publisher\":{\"@id\":\"https:\/\/www.omongateau.fr\/#\/schema\/person\/f4bcddbd180028225e24bc6f070a2a3c\"},\"image\":{\"@id\":\"https:\/\/www.omongateau.fr\/index.php\/2018\/07\/16\/black-forest\/#primaryimage\"},\"keywords\":\"cerise,f\\u00f4ret noire,griotte,kirsh,petit gateau,revisite\",\"articleSection\":\"G\\u00e2teaux et entremets\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.omongateau.fr\/index.php\/2018\/07\/16\/black-forest\/#respond\"]}]},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/www.omongateau.fr\/#\/schema\/person\/f4bcddbd180028225e24bc6f070a2a3c\",\"name\":\"Cl\\u00e9ment Lhoumeau\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.omongateau.fr\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.omongateau.fr\/wp-content\/uploads\/2018\/04\/Cl\\u00e9ment-Co0995-HD2.jpg\",\"width\":2000,\"height\":1600,\"caption\":\"Cl\\u00e9ment Lhoumeau\"},\"logo\":{\"@id\":\"https:\/\/www.omongateau.fr\/#personlogo\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.omongateau.fr\/index.php\/wp-json\/wp\/v2\/posts\/1288"}],"collection":[{"href":"https:\/\/www.omongateau.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.omongateau.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.omongateau.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.omongateau.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1288"}],"version-history":[{"count":9,"href":"https:\/\/www.omongateau.fr\/index.php\/wp-json\/wp\/v2\/posts\/1288\/revisions"}],"predecessor-version":[{"id":1325,"href":"https:\/\/www.omongateau.fr\/index.php\/wp-json\/wp\/v2\/posts\/1288\/revisions\/1325"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.omongateau.fr\/index.php\/wp-json\/wp\/v2\/media\/1291"}],"wp:attachment":[{"href":"https:\/\/www.omongateau.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.omongateau.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.omongateau.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}